{"id":18461,"date":"2024-09-30T09:15:02","date_gmt":"2024-09-30T12:15:02","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=18461"},"modified":"2024-09-30T09:15:04","modified_gmt":"2024-09-30T12:15:04","slug":"questao-110-enem-ppl-2013","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-110-enem-ppl-2013\/","title":{"rendered":"Quest\u00e3o 110 &#8211; ENEM PPL 2013"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Televis\u00e3o x cinema<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais uma vez, reacende-se o desgastante debate sobre \u201clinguagem de televis\u00e3o\u201d e \u201clinguagem de cinema\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No mesmo pa\u00eds em que pagar ingresso ainda \u00e9 luxo para milh\u00f5es de pessoas, alguns cr\u00edticos utilizam o termo \u201ctelevisivo\u201d para depreciar uma obra. E \u201ccinematogr\u00e1fico\u201d para enaltec\u00ea-la.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como se houvesse um juiz onipotente a permitir ou n\u00e3o que se sinta uma hist\u00f3ria da maneira que se pretende senti-la.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os sentidos ficam de fora da an\u00e1lise ignorante, tipicamente pol\u00edtica, que divorcia a t\u00e9cnica da percep\u00e7\u00e3o sensorial. E \u00e9 exatamente a\u00ed que reside o \u00fanico interesse de um realizador: o momento do encontro do espectador com a obra.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">MONJARDIM, J.&nbsp;<strong>O Globo<\/strong>, Rio de Janeiro, 24 set. 2004 (adaptado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao comentar o ressurgimento do debate sobre \u201clinguagem de televis\u00e3o\u201d e \u201clinguagem de cinema\u201d, o autor mostra a<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) import\u00e2ncia do debate para o entendimento destes dois diferentes meios de linguagem: a televis\u00e3o e o cinema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) atitude prepotente dos cr\u00edticos ao julgarem preconceituosamente as escolhas do p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) validade do debate para o aprimoramento da linguagem do cinema e da televis\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) neutralidade dos cr\u00edticos no uso das palavras \u201ctelevisivo\u201d e \u201ccinematogr\u00e1fico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) contribui\u00e7\u00e3o dos cr\u00edticos na valoriza\u00e7\u00e3o dos sentimentos do espectador.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No texto, o autor critica a atitude dos cr\u00edticos que utilizam os termos \u201ctelevisivo\u201d de forma depreciativa e \u201ccinematogr\u00e1fico\u201d de maneira enaltecedora. Essa postura \u00e9 considerada preconceituosa, pois ignora as diferentes formas de o p\u00fablico se conectar com uma obra, sem levar em considera\u00e7\u00e3o as percep\u00e7\u00f5es sensoriais que o espectador tem ao assistir tanto a televis\u00e3o quanto ao cinema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Televis\u00e3o x cinema Mais uma vez, reacende-se o desgastante debate sobre \u201clinguagem de televis\u00e3o\u201d e \u201clinguagem de cinema\u201d. No mesmo pa\u00eds em que pagar ingresso ainda \u00e9 luxo para milh\u00f5es de pessoas, alguns cr\u00edticos utilizam o termo \u201ctelevisivo\u201d para depreciar uma obra. E \u201ccinematogr\u00e1fico\u201d para enaltec\u00ea-la. Como se houvesse um juiz onipotente a permitir ou [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,92],"tags":[],"area-do-conhecimento":[117,126],"assunto":[],"class_list":["post-18461","post","type-post","status-publish","format-standard","hentry","category-questoes-ppl","category-2013-questoes-ppl","area-do-conhecimento-linguagens-codigos-e-suas-tecnologias","area-do-conhecimento-portugues"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=18461"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18461\/revisions"}],"predecessor-version":[{"id":18462,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18461\/revisions\/18462"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=18461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=18461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=18461"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=18461"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=18461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}