{"id":18496,"date":"2024-09-30T10:28:34","date_gmt":"2024-09-30T13:28:34","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=18496"},"modified":"2024-09-30T10:28:35","modified_gmt":"2024-09-30T13:28:35","slug":"questao-125-enem-ppl-2013","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-125-enem-ppl-2013\/","title":{"rendered":"Quest\u00e3o 125 &#8211; ENEM PPL 2013"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Uma l\u00edngua \u00e9 um sistema social reconhec\u00edvel em diferentes variedades e nos muitos usos que as pessoas fazem dela em m\u00faltiplas situa\u00e7\u00f5es de comunica\u00e7\u00e3o. O texto que se apresenta na variedade padr\u00e3o formal da l\u00edngua \u00e9<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) Quando voc\u00ea quis eu n\u00e3o quis<br>Qdo eu quis voc\u00ea \u00f1 quis<br>Pensando mal quase q fui<br>Feliz (Cacaso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) \u2014 Aonde \u00e9 que voc\u00ea vai, rapaz?!<br>\u2014 T\u00e1 louco, bicho, vou cair fora!<br>\u2014 Mas, qual \u00e9, rapaz?! Uma simples opera\u00e7\u00e3o de<br>apendicite! (Ziraldo) \u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) Eu, hoje, acordei mais cedo<br>e, azul, tive uma ideia clara.<br>S\u00f3 existe um segredo.<br>Tudo est\u00e1 na cara.  (Paulo Leminski) \u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) Com deus mi deito com deus mi levanto<br>comigo eu calo comigo eu canto<br>eu bato um papo eu bato um ponto<br>eu tomo um drink eu fico tonto. (Chacal) \u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) O tempo \u00e9 um fio<br>por entre os dedos.<br>Escapa o fio,<br>perdeu-se o tempo. (Henriqueta Lisboa) \u00a0\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O texto apresentado na alternativa <strong>E<\/strong> est\u00e1 na variedade padr\u00e3o formal da l\u00edngua, pois segue as normas gramaticais, de pontua\u00e7\u00e3o e de estilo que caracterizam o portugu\u00eas formal. Al\u00e9m disso, a estrutura frasal e o vocabul\u00e1rio empregados s\u00e3o t\u00edpicos de textos liter\u00e1rios que respeitam a norma culta, ao contr\u00e1rio das demais op\u00e7\u00f5es, que utilizam linguagem coloquial ou apresentam desvios propositais da norma padr\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa E<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma l\u00edngua \u00e9 um sistema social reconhec\u00edvel em diferentes variedades e nos muitos usos que as pessoas fazem dela em m\u00faltiplas situa\u00e7\u00f5es de comunica\u00e7\u00e3o. O texto que se apresenta na variedade padr\u00e3o formal da l\u00edngua \u00e9 A) Quando voc\u00ea quis eu n\u00e3o quisQdo eu quis voc\u00ea \u00f1 quisPensando mal quase q fuiFeliz (Cacaso) B) \u2014 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,92],"tags":[],"area-do-conhecimento":[117,126],"assunto":[],"class_list":["post-18496","post","type-post","status-publish","format-standard","hentry","category-questoes-ppl","category-2013-questoes-ppl","area-do-conhecimento-linguagens-codigos-e-suas-tecnologias","area-do-conhecimento-portugues"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=18496"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18496\/revisions"}],"predecessor-version":[{"id":18497,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18496\/revisions\/18497"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=18496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=18496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=18496"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=18496"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=18496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}