{"id":18498,"date":"2024-09-30T10:31:48","date_gmt":"2024-09-30T13:31:48","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=18498"},"modified":"2024-09-30T10:31:49","modified_gmt":"2024-09-30T13:31:49","slug":"questao-126-enem-ppl-2013","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-126-enem-ppl-2013\/","title":{"rendered":"Quest\u00e3o 126 &#8211; ENEM PPL 2013"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"675\" height=\"448\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/09\/A-foto-mostra-integrantes.png\" alt=\"\" class=\"wp-image-18499\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/09\/A-foto-mostra-integrantes.png 675w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/09\/A-foto-mostra-integrantes-300x199.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A foto mostra integrantes de um grupo de choro tocando instrumentos de diferentes classifica\u00e7\u00f5es. Nessa forma\u00e7\u00e3o, o instrumento que representa a fam\u00edlia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) das madeiras \u00e9 a flauta transversal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) das cordas friccionadas \u00e9 o bandolim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) dos metais \u00e9 o pandeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) das percuss\u00f5es com membrana \u00e9 o afox\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) das cordas percurtidas \u00e9 o cavaquinho.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A flauta transversal pertence \u00e0 fam\u00edlia das madeiras, apesar de muitas flautas modernas serem feitas de metal. Essa classifica\u00e7\u00e3o ocorre porque originalmente as flautas eram feitas de madeira e o som \u00e9 produzido pela vibra\u00e7\u00e3o da coluna de ar no tubo, sem o uso de palhetas. No conjunto de choro, ela \u00e9 um dos instrumentos respons\u00e1veis pelas melodias e ornamenta\u00e7\u00f5es caracter\u00edsticas desse estilo musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa A<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A foto mostra integrantes de um grupo de choro tocando instrumentos de diferentes classifica\u00e7\u00f5es. Nessa forma\u00e7\u00e3o, o instrumento que representa a fam\u00edlia A) das madeiras \u00e9 a flauta transversal. B) das cordas friccionadas \u00e9 o bandolim. C) dos metais \u00e9 o pandeiro. D) das percuss\u00f5es com membrana \u00e9 o afox\u00e9. E) das cordas percurtidas \u00e9 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":18499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,92],"tags":[],"area-do-conhecimento":[117,126],"assunto":[],"class_list":["post-18498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-ppl","category-2013-questoes-ppl","area-do-conhecimento-linguagens-codigos-e-suas-tecnologias","area-do-conhecimento-portugues"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=18498"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18498\/revisions"}],"predecessor-version":[{"id":18500,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18498\/revisions\/18500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/18499"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=18498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=18498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=18498"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=18498"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=18498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}