{"id":18506,"date":"2024-09-30T10:40:16","date_gmt":"2024-09-30T13:40:16","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=18506"},"modified":"2024-09-30T10:40:18","modified_gmt":"2024-09-30T13:40:18","slug":"questao-129-enem-ppl-2013","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-129-enem-ppl-2013\/","title":{"rendered":"Quest\u00e3o 129 &#8211; ENEM PPL 2013"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Como ganhar qualquer discuss\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A verdade nem sempre depende de fatos \u2014 nos jornais, no Congresso ou no boteco, ela \u00e9 frequentemente empacotada com t\u00e1ticas perversas e milenares. Conhecer essas t\u00e9cnicas \u00e9 um bom jeito de se defender contra elas (e fazer a sua opini\u00e3o prevalecer).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Capte a benevol\u00eancia<\/strong>&nbsp;\u2014 Siga a dica da ret\u00f3rica romana (captatio benevolentiae) e adule o interlocutor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Exagere o argumento do advers\u00e1rio<\/strong>&nbsp;\u2014 \u00c9 a \u201ct\u00e9cnica do espantalho\u201d, tamb\u00e9m chamada de amplia\u00e7\u00e3o indevida pelo fil\u00f3sofo Arthur Schopenhauer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Entre na onda<\/strong>&nbsp;\u2014 Concorde com parte dos argumentos do outro para, a partir da\u00ed, tra\u00e7ar a pr\u00f3pria conclus\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outras dicas do mal:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mantenha a calma (o tom de fala vale mais que bons argumentos).<\/li>\n\n\n\n<li>Invalide as opini\u00f5es do advers\u00e1rio, desqualificando-o sem question\u00e1-lo.<\/li>\n\n\n\n<li>Repita o argumento do outro, mas agora a seu favor.<\/li>\n\n\n\n<li>Revele que est\u00e1 usando uma t\u00e1tica para ganhar a discuss\u00e3o (aproveite para fingir que voc\u00ea venceu).<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">NARLOCH, L. Dispon\u00edvel em: http:\/\/super.abril.com.br. Acesso em: 27 out. 2011 (fragmento).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O fragmento, retirado de uma revista de divulga\u00e7\u00e3o cient\u00edfica, constr\u00f3i-se em tom de humor, a partir de uma linguagem l\u00fadica e despojada. O apelo a esse recurso expressivo \u00e9 adequado para essa situa\u00e7\u00e3o comunicativa, porque<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) converge para a subjetividade, caracter\u00edstica desse tipo de peri\u00f3dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) segue par\u00e2metros textuais semelhantes aos das publica\u00e7\u00f5es cient\u00edficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) confirma o pr\u00f3prio peri\u00f3dico como meio de comunica\u00e7\u00e3o de massa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) atende a um leitor interessado em expandir conhecimento te\u00f3rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) contraria o uso previsto para o registro formal da l\u00edngua portuguesa.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O texto adota um tom humor\u00edstico e uma linguagem leve para tornar o conte\u00fado mais acess\u00edvel e interessante ao leitor. Esse recurso expressivo \u00e9 adequado para uma revista de divulga\u00e7\u00e3o cient\u00edfica, pois atende a um p\u00fablico mais amplo e diversificado, interessado em expandir seu conhecimento de forma descontra\u00edda, sem perder o car\u00e1ter informativo. A linguagem simples e o uso de humor ajudam a transmitir informa\u00e7\u00f5es de maneira mais envolvente, caracter\u00edstica de meios de comunica\u00e7\u00e3o de massa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa C<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como ganhar qualquer discuss\u00e3o A verdade nem sempre depende de fatos \u2014 nos jornais, no Congresso ou no boteco, ela \u00e9 frequentemente empacotada com t\u00e1ticas perversas e milenares. Conhecer essas t\u00e9cnicas \u00e9 um bom jeito de se defender contra elas (e fazer a sua opini\u00e3o prevalecer). 1. Capte a benevol\u00eancia&nbsp;\u2014 Siga a dica da ret\u00f3rica [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,92],"tags":[],"area-do-conhecimento":[117,126],"assunto":[],"class_list":["post-18506","post","type-post","status-publish","format-standard","hentry","category-questoes-ppl","category-2013-questoes-ppl","area-do-conhecimento-linguagens-codigos-e-suas-tecnologias","area-do-conhecimento-portugues"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=18506"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18506\/revisions"}],"predecessor-version":[{"id":18507,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/18506\/revisions\/18507"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=18506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=18506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=18506"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=18506"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=18506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}