{"id":23437,"date":"2025-11-18T19:18:11","date_gmt":"2025-11-18T22:18:11","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=23437"},"modified":"2025-11-18T19:18:13","modified_gmt":"2025-11-18T22:18:13","slug":"questao-140-enem-2025","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-140-enem-2025\/","title":{"rendered":"Quest\u00e3o 140 &#8211; ENEM 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em um laborat\u00f3rio, um recipiente cont\u00e9m 10 litros de uma solu\u00e7\u00e3o composta apenas pelas subst\u00e2ncias <strong>S\u2081<\/strong> e <strong>S\u2082<\/strong>. Dessa solu\u00e7\u00e3o, <strong>99,95% \u00e9 de S\u2081<\/strong>. Uma quantidade de <strong>S\u2081<\/strong> ser\u00e1 retirada dessa solu\u00e7\u00e3o, mantendo a quantidade inicial de <strong>S\u2082<\/strong>, de modo que <strong>99,90% da nova solu\u00e7\u00e3o seja de S\u2081<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qual \u00e9 a quantidade de <strong>S\u2081<\/strong>, em litro, que ser\u00e1 retirada?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 0,0050<br>B 0,0100<br>C 0,5000<br>D 4,9775<br>E 5,0000<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabendo que 99,95% de 10L s\u00e3o da solu\u00e7\u00e3o S1 podemos afirmar o restante \u00e9 S2, com isso podemos calcular quantos mL de S2 tem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">99,95% de 10L = 9995 mL de S1, restando ent\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10000 &#8211; 9995 = 5 mL de S2<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chamemos de x o volume novo de S1, queremos que esse valor seja 99,9% do conte\u00fado total, sendo o conte\u00fado total novo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">x + 5 mL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">queremos que<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">x\/(x+5) = 99,9\/100<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Multiplicando cruzado temos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">100x = 99,9x + 499,5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">0,1x = 499,5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">x = 499,5\/0,1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">x = 4995 mL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O comando pede o volume RETIRADO ent\u00e3o temos qque fazer<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9995 &#8211; 4995 = 5000 mL = 5 L = 5,000 L<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa E<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em um laborat\u00f3rio, um recipiente cont\u00e9m 10 litros de uma solu\u00e7\u00e3o composta apenas pelas subst\u00e2ncias S\u2081 e S\u2082. Dessa solu\u00e7\u00e3o, 99,95% \u00e9 de S\u2081. Uma quantidade de S\u2081 ser\u00e1 retirada dessa solu\u00e7\u00e3o, mantendo a quantidade inicial de S\u2082, de modo que 99,90% da nova solu\u00e7\u00e3o seja de S\u2081. Qual \u00e9 a quantidade de S\u2081, em [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,186],"tags":[],"area-do-conhecimento":[132,118],"assunto":[58],"class_list":["post-23437","post","type-post","status-publish","format-standard","hentry","category-questoes-do-enem","category-2025-questoes-enem-regular","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-porcentagem"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=23437"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23437\/revisions"}],"predecessor-version":[{"id":23438,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23437\/revisions\/23438"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=23437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=23437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=23437"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=23437"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=23437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}