{"id":23614,"date":"2026-04-10T07:45:30","date_gmt":"2026-04-10T10:45:30","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=23614"},"modified":"2026-04-10T07:45:31","modified_gmt":"2026-04-10T10:45:31","slug":"desafio-98","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/desafio-98\/","title":{"rendered":"Qual a altura da mesa?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><sup>Qual a altura da mesa?<\/sup><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"774\" height=\"233\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2026\/04\/image-1.png\" alt=\"\" class=\"wp-image-23616\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2026\/04\/image-1.png 774w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2026\/04\/image-1-300x90.png 300w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2026\/04\/image-1-768x231.png 768w\" sizes=\"(max-width: 774px) 100vw, 774px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>A) 120<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>B) 130<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>C) 140<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>D) 150<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>E) 160<\/sup><\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong><sup>Resolu\u00e7\u00e3o<\/sup><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>Vamos chamar de M a altura da mesa, G a altura do gato e T a altura da tartaruga. Com a primeira imagem podemos afirmar que<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>M + G &#8211; T = 170 cm&nbsp; &nbsp; (1)<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>E a partir da segunda imagem<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>M &#8211; G + T = 130 cm &nbsp; (2)<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>Fazendo a equa\u00e7\u00e3o (1) + (2) teremos<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>M + G &#8211; T +( M &#8211; G + T) = 170 + 130<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>M + M + G &#8211; G &#8211; T + T = 300<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>2M = 300<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>Dividindo por dois os dois lados, temos<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>M = 150 cm<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><sup>Alternativa D<\/sup><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qual a altura da mesa? A) 120 B) 130 C) 140 D) 150 E) 160 Resolu\u00e7\u00e3o Vamos chamar de M a altura da mesa, G a altura do gato e T a altura da tartaruga. Com a primeira imagem podemos afirmar que M + G &#8211; T = 170 cm&nbsp; &nbsp; (1) E a partir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23616,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[],"area-do-conhecimento":[],"assunto":[],"class_list":["post-23614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-extras"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=23614"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23614\/revisions"}],"predecessor-version":[{"id":23617,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/23614\/revisions\/23617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/23616"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=23614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=23614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=23614"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=23614"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=23614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}