{"id":3168,"date":"2023-10-13T23:10:39","date_gmt":"2023-10-14T02:10:39","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=3168"},"modified":"2024-02-08T10:09:14","modified_gmt":"2024-02-08T13:09:14","slug":"questao-138-enem-2015","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-138-enem-2015\/","title":{"rendered":"Quest\u00e3o 138 &#8211; ENEM 2015"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Quest\u00e3o 138 &#8211; Interpreta\u00e7\u00e3o de Gr\u00e1fico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente existem diversas locadoras de ve\u00edculos, permitindo uma concorr\u00eancia saud\u00e1vel para o mercado, fazendo com que os pre\u00e7os se tornem acess\u00edveis. Nas <strong>locadoras P e Q,<\/strong> o valor da di\u00e1ria de seus carros <strong>depende da dist\u00e2ncia percorrida<\/strong>, conforme o gr\u00e1fico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"446\" height=\"484\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-3.png\" alt=\"\" class=\"wp-image-3169\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-3.png 446w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-3-276x300.png 276w\" sizes=\"(max-width: 446px) 100vw, 446px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>valor pago na locadora Q \u00e9 menor ou igual \u00e0quele pago na locadora P para dist\u00e2ncias, em quil\u00f4metros, presentes em qual(is) intervalo(s)?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) De 20 a 100.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) De 80 a 130.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) De 100 a 160.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) De 0 a 20 e de 100 a 160.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) De 40 a 80 e de 130 a 160.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queremos descobrir em que momentos a curva Q est\u00e1 abaixo de P.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Observando o gr\u00e1fico do instante 0 ao 20 Q&lt;P e do instante 100 ao 160 tamb\u00e9m.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"929\" height=\"1024\" data-src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-4-929x1024.png\" alt=\"\" class=\"wp-image-3170 lazyload\" title=\"\" data-srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-4-929x1024.png 929w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-4-272x300.png 272w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-4-768x847.png 768w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-4.png 987w\" data-sizes=\"(max-width: 929px) 100vw, 929px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 929px; --smush-placeholder-aspect-ratio: 929\/1024;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa D<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00e3o 138 &#8211; Interpreta\u00e7\u00e3o de Gr\u00e1fico Atualmente existem diversas locadoras de ve\u00edculos, permitindo uma concorr\u00eancia saud\u00e1vel para o mercado, fazendo com que os pre\u00e7os se tornem acess\u00edveis. Nas locadoras P e Q, o valor da di\u00e1ria de seus carros depende da dist\u00e2ncia percorrida, conforme o gr\u00e1fico. O valor pago na locadora Q \u00e9 menor ou [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,24],"tags":[],"area-do-conhecimento":[132,118],"assunto":[51],"class_list":["post-3168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-do-enem","category-24","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-interpretacao-de-graficos"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3168"}],"version-history":[{"count":0,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/3170"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3168"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=3168"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=3168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}