{"id":3183,"date":"2023-10-13T23:21:01","date_gmt":"2023-10-14T02:21:01","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=3183"},"modified":"2024-05-23T09:24:35","modified_gmt":"2024-05-23T12:24:35","slug":"questao-143-enem-2015","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-143-enem-2015\/","title":{"rendered":"Quest\u00e3o 143 &#8211; ENEM 2015"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Quest\u00e3o 143 &#8211; Estat\u00edstica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em uma seletiva para a final dos 100 metros livres de nata\u00e7\u00e3o, numa olimp\u00edada, os atletas, em suas respectivas raias, obtiveram os seguintes tempos:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"585\" height=\"118\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-8.png\" alt=\"\" class=\"wp-image-3184\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-8.png 585w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-8-300x61.png 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>mediana dos tempos apresentados<\/strong> no quadro \u00e9<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 20,70.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 20,77.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 20,80.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 20,85.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 20,90.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temos 8 tempos, precisamos colocar em ordem crescente e fazer uma m\u00e9dia entre o 4o tempo e o 5o tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,50<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,60<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,60<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,80<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,90<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,90<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,90<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20,96<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O quarto termo \u00e9 20,80 e o quinto 20,90<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(20,80 + 20,90)\/2 = 41,70\/2 = 20,85<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa D<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00e3o 143 &#8211; Estat\u00edstica Em uma seletiva para a final dos 100 metros livres de nata\u00e7\u00e3o, numa olimp\u00edada, os atletas, em suas respectivas raias, obtiveram os seguintes tempos: A mediana dos tempos apresentados no quadro \u00e9 A) 20,70. B) 20,77. C) 20,80. D) 20,85. E) 20,90. Solu\u00e7\u00e3o Temos 8 tempos, precisamos colocar em ordem crescente [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3184,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,24],"tags":[],"area-do-conhecimento":[132,118],"assunto":[56],"class_list":["post-3183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-do-enem","category-24","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-estatistica"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3183"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3183\/revisions"}],"predecessor-version":[{"id":6174,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3183\/revisions\/6174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/3184"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3183"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=3183"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=3183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}