{"id":3196,"date":"2023-10-13T23:31:44","date_gmt":"2023-10-14T02:31:44","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=3196"},"modified":"2024-02-08T10:29:01","modified_gmt":"2024-02-08T13:29:01","slug":"questao-148-enem-2015","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-148-enem-2015\/","title":{"rendered":"Quest\u00e3o 148 &#8211; ENEM 2015"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Quest\u00e3o 148 &#8211; Geometria Espacial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma carga de <strong>100 cont\u00eaineres<\/strong>, id\u00eanticos ao modelo apresentado na Figura 1, dever\u00e1 ser descarregada no porto de uma cidade. Para isso, uma <strong>\u00e1rea retangular de 10 m por 32 m foi cedida para o empilhamento desses cont\u00eaineres<\/strong> (Figura 2).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"591\" height=\"1024\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-11-591x1024.png\" alt=\"\" class=\"wp-image-3197\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-11-591x1024.png 591w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-11-173x300.png 173w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-11.png 596w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com as normas desse porto, os <strong>cont\u00eaineres dever\u00e3o ser empilhados de forma a n\u00e3o sobrarem espa\u00e7os nem ultrapassarem a \u00e1rea delimitada.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o empilhamento total da carga e atendendo \u00e0 norma do porto, a <strong>altura m\u00ednima a ser atingida por essa pilha de cont\u00eaineres \u00e9<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 12,5 m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 17,5 m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 25,0 m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 22,5 m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 32,5 m.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber quantos containers cabem no espa\u00e7o retangular podemos dividir o comprimento do espa\u00e7o com o comprimento do cont\u00eainer e fazer o mesmo com a largura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprimento por comprimento: 32\/6,4 = 5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Largura por largura: 10\/2,5 = 4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o cabe um total de 5.4 = 20 cont\u00eaineres no primeiro andar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se s\u00e3o 100 cont\u00eaineres \u00e9 necess\u00e1rio empilhar mais 80.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo 20 em cada andar, temos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">80\/20 = 4 andares al\u00e9m do primeiro, ou seja, 5 andares no total<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5 andares de 2,5 m equivale a uma altura total de:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2,5.5 = 12,5m<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa A<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00e3o 148 &#8211; Geometria Espacial Uma carga de 100 cont\u00eaineres, id\u00eanticos ao modelo apresentado na Figura 1, dever\u00e1 ser descarregada no porto de uma cidade. Para isso, uma \u00e1rea retangular de 10 m por 32 m foi cedida para o empilhamento desses cont\u00eaineres (Figura 2). De acordo com as normas desse porto, os cont\u00eaineres dever\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3197,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,24],"tags":[],"area-do-conhecimento":[132,118],"assunto":[54],"class_list":["post-3196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-do-enem","category-24","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-geometria-espacial"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3196"}],"version-history":[{"count":0,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/3197"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3196"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=3196"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=3196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}