{"id":3441,"date":"2023-10-31T15:15:31","date_gmt":"2023-10-31T18:15:31","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=3441"},"modified":"2024-02-08T11:45:17","modified_gmt":"2024-02-08T14:45:17","slug":"questao-153-enem-2014","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-153-enem-2014\/","title":{"rendered":"Quest\u00e3o 153 &#8211; ENEM 2014"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Quest\u00e3o 153 &#8211; Interpreta\u00e7\u00e3o de gr\u00e1ficos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma empresa de alimentos oferece tr\u00eas valores diferentes de remunera\u00e7\u00e3o a seus funcion\u00e1rios, de acordo com o grau de instru\u00e7\u00e3o necess\u00e1rio para cada cargo. No ano de 2013, a empresa teve uma receita de 10 milh\u00f5es de reais por m\u00eas e um gasto mensal com a folha salarial de <strong>R$ 400 000,00, distribu\u00eddos de acordo com o Gr\u00e1fico 1<\/strong>. No ano seguinte, a&nbsp; ampliar\u00e1 o n\u00famero de funcion\u00e1rios, mantendo o mesmo valor salarial para cada categoria. <strong>Os demais custos da empresa permanecer\u00e3o constantes de 2013 para 2014. O n\u00famero de funcion\u00e1rios em 2013 e 2014, por grau de instru\u00e7\u00e3o, est\u00e1 no Gr\u00e1fico 2.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"602\" height=\"854\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-68.png\" alt=\"\" class=\"wp-image-3442\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-68.png 602w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/10\/Imagem-PNG-68-211x300.png 211w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Qual deve ser o <strong>aumento na receita da empresa para que o lucro mensal em 2014 seja o mesmo de 2013?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) R$ 114 285,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) R$ 130 000,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) R$ 160 000,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) R$ 210 000,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) R$ 213 333,00<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2013 a empresa pagava 75% de 400 000 reais para os funcion\u00e1rios com ensino m\u00e9dio completo, ou seja<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">0,75 . 400 000 = 300 000 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os 100 000 restantes ser\u00e3o distribu\u00eddos igualmente entre os 2 grupos de funcion\u00e1rios restantes de ensino fundamental completo e ensino superior ficando cada um com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">100 000\/2 = 50 000 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos dividir o total de cada categoria pela quantidade de funcion\u00e1rios de 2013 em cada categoria para descobrir o sal\u00e1rio de cada funcion\u00e1rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensino Fundamental: 50 000 \/ 50 = 1000 reais por funcion\u00e1rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensino M\u00e9dio: 300 000 \/ 150 = 2000 reais por funcion\u00e1rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensino Superior: 50 000 \/ 10 = 5000 reais por funcion\u00e1rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2014 a quantidade de funcion\u00e1rios em cada categoria aumentou em&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EF: 70 &#8211; 50 = 20<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EM: 180 &#8211; 150 = 30<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ES: 20 &#8211; 10 = 10<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o a arrecada\u00e7\u00e3o deve ser proporcional ao aumento de cada categoria:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EF: 20 . 1000 = 20 000 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EM: 30 . 2000 = 60 000 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ES: 10 . 5000 = 50 000 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somando tudo o aumento deve ser de&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20 000 + 60 000 + 50 000 = 130 000 reais a mais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00e3o 153 &#8211; Interpreta\u00e7\u00e3o de gr\u00e1ficos Uma empresa de alimentos oferece tr\u00eas valores diferentes de remunera\u00e7\u00e3o a seus funcion\u00e1rios, de acordo com o grau de instru\u00e7\u00e3o necess\u00e1rio para cada cargo. No ano de 2013, a empresa teve uma receita de 10 milh\u00f5es de reais por m\u00eas e um gasto mensal com a folha salarial de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,25],"tags":[],"area-do-conhecimento":[132,118],"assunto":[51],"class_list":["post-3441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-do-enem","category-25","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-interpretacao-de-graficos"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3441"}],"version-history":[{"count":0,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/3442"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3441"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=3441"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=3441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}