{"id":3474,"date":"2023-11-01T08:17:52","date_gmt":"2023-11-01T11:17:52","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=3474"},"modified":"2024-02-08T11:58:31","modified_gmt":"2024-02-08T14:58:31","slug":"questao-162-enem-2014","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-162-enem-2014\/","title":{"rendered":"Quest\u00e3o 162 &#8211; ENEM 2014"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Quest\u00e3o 162 &#8211; Fun\u00e7\u00e3o de 1o Grau<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em uma cidade, o valor total da conta de energia el\u00e9trica \u00e9 obtido pelo produto entre o consumo (em kWh) e o valor da tarifa do kWh (com tributos), adicionado \u00e0 Cosip (contribui\u00e7\u00e3o para custeio da ilumina\u00e7\u00e3o p\u00fablica), conforme a express\u00e3o:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valor do kWh (com tributos) x consumo (em kWh) + Cosip<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O valor da Cosip \u00e9 fixo em cada faixa de consumo.&nbsp; O quadro mostra o valor cobrado para algumas faixas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"821\" height=\"264\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/11\/Imagem-PNG-13.png\" alt=\"\" class=\"wp-image-3475\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/11\/Imagem-PNG-13.png 821w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/11\/Imagem-PNG-13-300x96.png 300w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2023\/11\/Imagem-PNG-13-768x247.png 768w\" sizes=\"(max-width: 821px) 100vw, 821px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Suponha que, em uma resid\u00eancia, todo <strong>m\u00eas o consumo seja de 150 kWh, e o valor do kWh (com tributos) seja de R$ 0,50. O morador dessa resid\u00eancia pretende diminuir seu consumo mensal de energia el\u00e9trica com o objetivo de reduzir o custo total da conta em pelo menos 10%.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qual deve ser o <strong>consumo m\u00e1ximo, em kWh<\/strong>, dessa resid\u00eancia para produzir a redu\u00e7\u00e3o pretendida pelo morador?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 134,1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 135,0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 137,1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 138,6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 143,1<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se o consumo mensal da fam\u00edlia \u00e9 150kWh com 0,50 centavos por kWh e uma tarifa de 4,50 reais, o gasto mensal \u00e9<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">150.0,50 + 4,50 = 79,50<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queremos uma redu\u00e7\u00e3o de 10%, ou seja o novo pre\u00e7o deve ser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">79,50 . 0,90 = 71,55 reais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos analisar as faixas de maior consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Superior a 140 at\u00e9 200:<\/strong> com a cosip a 4,50, restam&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">71,55 &#8211; 4,50 = 67,05 de taxa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo o preco do kWh 0,50 centavos, ser\u00e3o necess\u00e1rios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">67,05\/0,50 = 134,10 kWh, mas na faixa o valor m\u00ednimo \u00e9 140, ent\u00e3o n\u00e3o se encontra nessa faixa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Superior a 100 at\u00e9 140: <\/strong>com a cosip a 3,00 restam<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">71,55 &#8211; 3 = 68,55 reais de taxa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dividindo pelo pre\u00e7o de cada kWh<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">68,55\/0,5 = 137,10<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que se encontra nessa faixa, ou seja, esse \u00e9 a maior quantidade de kWh que deve ser consumida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa C<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00e3o 162 &#8211; Fun\u00e7\u00e3o de 1o Grau Em uma cidade, o valor total da conta de energia el\u00e9trica \u00e9 obtido pelo produto entre o consumo (em kWh) e o valor da tarifa do kWh (com tributos), adicionado \u00e0 Cosip (contribui\u00e7\u00e3o para custeio da ilumina\u00e7\u00e3o p\u00fablica), conforme a express\u00e3o: Valor do kWh (com tributos) x consumo [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3475,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,25],"tags":[],"area-do-conhecimento":[132,118],"assunto":[52],"class_list":["post-3474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-do-enem","category-25","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-funcao-de-1o-grau"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3474"}],"version-history":[{"count":0,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/3474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/3475"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3474"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=3474"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=3474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}