{"id":7003,"date":"2024-06-30T22:23:21","date_gmt":"2024-07-01T01:23:21","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=7003"},"modified":"2024-09-05T14:57:01","modified_gmt":"2024-09-05T17:57:01","slug":"questao-153-enem-ppl-2017","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-153-enem-ppl-2017\/","title":{"rendered":"Quest\u00e3o 153 &#8211; ENEM PPL 2017"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O h\u00e1bito cristalino \u00e9 um termo utilizado por mineralogistas para descrever a apar\u00eancia t\u00edpica de um cristal em termos de tamanho e forma. A granada \u00e9 um mineral cujo h\u00e1bito cristalino \u00e9 um <strong>poliedro com 30 arestas e 20 v\u00e9rtices.<\/strong> Um mineralogista construiu um modelo ilustrativo de um cristal de granada pela jun\u00e7\u00e3o dos pol\u00edgonos correspondentes \u00e0s faces.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Supondo que o poliedro ilustrativo de um cristal de granada \u00e9 convexo, ent\u00e3o a quantidade de faces utilizadas na montagem do modelo ilustrativo desse cristal \u00e9 igual a&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 10.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 12.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 25.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 42.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 50.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Resolu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembremos da f\u00f3rmula que nos diz que em um poliedro convexo, sendo V o n\u00famero de v\u00e9rtices, F e o n\u00famero de faces, A o n\u00famero de arestas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V + F = A + 2<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se temos 30 arestas e 20 v\u00e9rtices, substituindo na equa\u00e7\u00e3o temos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20 + F = 30 + 2<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F = 32 &#8211; 20<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F = 12<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O h\u00e1bito cristalino \u00e9 um termo utilizado por mineralogistas para descrever a apar\u00eancia t\u00edpica de um cristal em termos de tamanho e forma. A granada \u00e9 um mineral cujo h\u00e1bito cristalino \u00e9 um poliedro com 30 arestas e 20 v\u00e9rtices. Um mineralogista construiu um modelo ilustrativo de um cristal de granada pela jun\u00e7\u00e3o dos pol\u00edgonos [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,96],"tags":[],"area-do-conhecimento":[132,118],"assunto":[54],"class_list":["post-7003","post","type-post","status-publish","format-standard","hentry","category-questoes-ppl","category-2017-questoes-ppl","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-geometria-espacial"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7003"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7003\/revisions"}],"predecessor-version":[{"id":7004,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7003\/revisions\/7004"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7003"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=7003"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=7003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}