{"id":7010,"date":"2024-06-30T22:30:00","date_gmt":"2024-07-01T01:30:00","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=7010"},"modified":"2024-09-05T14:57:01","modified_gmt":"2024-09-05T17:57:01","slug":"questao-156-enem-ppl-2017","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/questao-156-enem-ppl-2017\/","title":{"rendered":"Quest\u00e3o 156 &#8211; ENEM PPL 2017"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O gr\u00e1fico mostra a expans\u00e3o da base de assinantes de telefonia celular no Brasil, em milh\u00f5es de unidades, no per\u00edodo de 2006 a 2011.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"393\" height=\"189\" src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/06\/O-grafico-mostra-a.png\" alt=\"\" class=\"wp-image-7011\" title=\"\" srcset=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/06\/O-grafico-mostra-a.png 393w, https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/06\/O-grafico-mostra-a-300x144.png 300w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>De acordo com o gr\u00e1fico, a taxa de crescimento do n\u00famero de aparelhos celulares no Brasil, de 2007 para 2011, foi de&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 8,53%&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 85,17%&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 103,04%&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 185,17%&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 345,00%<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Resolu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para calcular a taxa de crescimento de 2007 a 2011 basta calcular a raz\u00e3o entre o n\u00famero em 2011 e em 2007 e tirar 100% desse valor<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">224,02\/120,98 = 1,852 = 185,2%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Houve um aumento de 85,2%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O gr\u00e1fico mostra a expans\u00e3o da base de assinantes de telefonia celular no Brasil, em milh\u00f5es de unidades, no per\u00edodo de 2006 a 2011. De acordo com o gr\u00e1fico, a taxa de crescimento do n\u00famero de aparelhos celulares no Brasil, de 2007 para 2011, foi de&nbsp; A) 8,53%&nbsp; B) 85,17%&nbsp; C) 103,04%&nbsp; D) 185,17%&nbsp; E) [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,96],"tags":[],"area-do-conhecimento":[132,118],"assunto":[58],"class_list":["post-7010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questoes-ppl","category-2017-questoes-ppl","area-do-conhecimento-matematica","area-do-conhecimento-matematica-e-suas-tecnologias","assunto-porcentagem"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7010"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7010\/revisions"}],"predecessor-version":[{"id":7012,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7010\/revisions\/7012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media\/7011"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7010"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=7010"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=7010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}