{"id":7163,"date":"2024-07-07T15:59:08","date_gmt":"2024-07-07T18:59:08","guid":{"rendered":"https:\/\/xequematenem.com.br\/blog\/?p=7163"},"modified":"2024-07-07T15:59:37","modified_gmt":"2024-07-07T18:59:37","slug":"desafio-17","status":"publish","type":"post","link":"https:\/\/xequematenem.com.br\/blog\/desafio-17\/","title":{"rendered":"Quanto \u00e9&#8230;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quanto \u00e9\u00a02% de 5%\u00a0?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A) 0,1%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B) 1%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C) 2,5%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D) 10%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E) 25%<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>Solu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabemos que<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2% = 2\/100&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E que<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5% = 5\/100&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o temos que, pela propriedade de porcentagem<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"240\" height=\"50\" data-src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/07\/image.png\" alt=\"\" class=\"wp-image-7164 lazyload\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 240px; --smush-placeholder-aspect-ratio: 240\/50;\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Multiplicando as fra\u00e7\u00f5es temos:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"221\" height=\"48\" data-src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/07\/image-1.png\" alt=\"\" class=\"wp-image-7165 lazyload\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 221px; --smush-placeholder-aspect-ratio: 221\/48;\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Simplificando para que o denominador seja 100, assim como \u00e9 em porcentagem, teremos<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"214\" height=\"47\" data-src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/07\/image-2.png\" alt=\"\" class=\"wp-image-7166 lazyload\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 214px; --smush-placeholder-aspect-ratio: 214\/47;\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Que em porcentagem quer dizer<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"127\" height=\"55\" data-src=\"https:\/\/xequematenem.com.br\/blog\/wp-content\/uploads\/2024\/07\/image-3.png\" alt=\"\" class=\"wp-image-7167 lazyload\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 127px; --smush-placeholder-aspect-ratio: 127\/55;\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alternativa A<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quanto \u00e9\u00a02% de 5%\u00a0? A) 0,1% B) 1% C) 2,5% D) 10% E) 25% Solu\u00e7\u00e3o Sabemos que 2% = 2\/100&nbsp; E que 5% = 5\/100&nbsp; Ent\u00e3o temos que, pela propriedade de porcentagem Multiplicando as fra\u00e7\u00f5es temos: Simplificando para que o denominador seja 100, assim como \u00e9 em porcentagem, teremos Que em porcentagem quer dizer Alternativa [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[],"area-do-conhecimento":[],"assunto":[58],"class_list":["post-7163","post","type-post","status-publish","format-standard","hentry","category-questoes-extras","assunto-porcentagem"],"_links":{"self":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7163"}],"version-history":[{"count":1,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7163\/revisions"}],"predecessor-version":[{"id":7168,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/posts\/7163\/revisions\/7168"}],"wp:attachment":[{"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7163"},{"taxonomy":"area-do-conhecimento","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/area-do-conhecimento?post=7163"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/xequematenem.com.br\/blog\/wp-json\/wp\/v2\/assunto?post=7163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}